{"id":5451,"date":"2025-09-16T21:00:19","date_gmt":"2025-09-16T19:00:19","guid":{"rendered":"https:\/\/www.topclassics.com\/notre-collection\/mercedes-benz-amg-gts\/"},"modified":"2025-09-16T21:00:19","modified_gmt":"2025-09-16T19:00:19","slug":"mercedes-benz-amg-gts","status":"publish","type":"notre-collection","link":"https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/","title":{"rendered":"Mercedes-Benz AMG GTS"},"content":{"rendered":"","protected":false},"template":"","class_list":["post-5451","notre-collection","type-notre-collection","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercedes-Benz AMG GTS Matt grey - Top Classics - Restauration de Voitures Anciennes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercedes-Benz AMG GTS Matt grey - Top Classics - Restauration de Voitures Anciennes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/\" \/>\n<meta property=\"og:site_name\" content=\"Top Classics - Restauration de Voitures Anciennes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/our-collection\\\/mercedes-benz-amg-gts\\\/\",\"url\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/our-collection\\\/mercedes-benz-amg-gts\\\/\",\"name\":\"Mercedes-Benz AMG GTS Matt grey - Top Classics - Restauration de Voitures Anciennes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/#website\"},\"datePublished\":\"2025-09-16T19:00:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/our-collection\\\/mercedes-benz-amg-gts\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.topclassics.com\\\/en\\\/our-collection\\\/mercedes-benz-amg-gts\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/our-collection\\\/mercedes-benz-amg-gts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notre Collection\",\"item\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/our-collection\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mercedes-Benz AMG GTS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/\",\"name\":\"Top Classics - Restauration de Voitures Anciennes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.topclassics.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercedes-Benz AMG GTS Matt grey - Top Classics - Restauration de Voitures Anciennes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/","og_locale":"en_US","og_type":"article","og_title":"Mercedes-Benz AMG GTS Matt grey - Top Classics - Restauration de Voitures Anciennes","og_url":"https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/","og_site_name":"Top Classics - Restauration de Voitures Anciennes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/","url":"https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/","name":"Mercedes-Benz AMG GTS Matt grey - Top Classics - Restauration de Voitures Anciennes","isPartOf":{"@id":"https:\/\/www.topclassics.com\/en\/#website"},"datePublished":"2025-09-16T19:00:19+00:00","breadcrumb":{"@id":"https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.topclassics.com\/en\/our-collection\/mercedes-benz-amg-gts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.topclassics.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Notre Collection","item":"https:\/\/www.topclassics.com\/en\/our-collection\/"},{"@type":"ListItem","position":3,"name":"Mercedes-Benz AMG GTS"}]},{"@type":"WebSite","@id":"https:\/\/www.topclassics.com\/en\/#website","url":"https:\/\/www.topclassics.com\/en\/","name":"Top Classics - Restauration de Voitures Anciennes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.topclassics.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.topclassics.com\/en\/wp-json\/wp\/v2\/notre-collection\/5451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.topclassics.com\/en\/wp-json\/wp\/v2\/notre-collection"}],"about":[{"href":"https:\/\/www.topclassics.com\/en\/wp-json\/wp\/v2\/types\/notre-collection"}],"wp:attachment":[{"href":"https:\/\/www.topclassics.com\/en\/wp-json\/wp\/v2\/media?parent=5451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}